{"id":151120,"date":"2025-07-08T08:01:36","date_gmt":"2025-07-08T08:01:36","guid":{"rendered":"https:\/\/www.decolor.com\/?post_type=ficha-de-seguridad&#038;p=151120"},"modified":"2025-07-08T08:01:36","modified_gmt":"2025-07-08T08:01:36","slug":"24151_deco-epoxi-2c-ld-24151-b_es","status":"publish","type":"ficha-de-seguridad","link":"https:\/\/www.decolor.com\/es\/ficha-de-seguridad\/24151_deco-epoxi-2c-ld-24151-b_es\/","title":{"rendered":"24151_DECO-EPOXI 2C LD 24151 (B)_ES"},"template":"","class_list":["post-151120","ficha-de-seguridad","type-ficha-de-seguridad","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>24151_DECO-EPOXI 2C LD 24151 (B)_ES - Decolor<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"24151_DECO-EPOXI 2C LD 24151 (B)_ES - Decolor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.decolor.com\/es\/ficha-de-seguridad\/24151_deco-epoxi-2c-ld-24151-b_es\/\" \/>\n<meta property=\"og:site_name\" content=\"Decolor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/pt\\\/ficha-de-seguridad\\\/24151_deco-epoxi-2c-ld-24151-b_es\\\/\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/pt\\\/ficha-de-seguridad\\\/24151_deco-epoxi-2c-ld-24151-b_es\\\/\",\"name\":\"24151_DECO-EPOXI 2C LD 24151 (B)_ES - Decolor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#website\"},\"datePublished\":\"2025-07-08T08:01:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/pt\\\/ficha-de-seguridad\\\/24151_deco-epoxi-2c-ld-24151-b_es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.decolor.com\\\/pt\\\/ficha-de-seguridad\\\/24151_deco-epoxi-2c-ld-24151-b_es\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/pt\\\/ficha-de-seguridad\\\/24151_deco-epoxi-2c-ld-24151-b_es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.decolor.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fichas de Seguridad\",\"item\":\"https:\\\/\\\/www.decolor.com\\\/es\\\/fichas-de-seguridad\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"24151_DECO-EPOXI 2C LD 24151 (B)_ES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/\",\"name\":\"Decolor\",\"description\":\"Web Decolor\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#organization\",\"name\":\"Decolor\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/marca_principal_pinturas_decolor_color.png\",\"contentUrl\":\"https:\\\/\\\/www.decolor.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/marca_principal_pinturas_decolor_color.png\",\"width\":1588,\"height\":421,\"caption\":\"Decolor\"},\"image\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"24151_DECO-EPOXI 2C LD 24151 (B)_ES - Decolor","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"24151_DECO-EPOXI 2C LD 24151 (B)_ES - Decolor","og_url":"https:\/\/www.decolor.com\/es\/ficha-de-seguridad\/24151_deco-epoxi-2c-ld-24151-b_es\/","og_site_name":"Decolor","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.decolor.com\/pt\/ficha-de-seguridad\/24151_deco-epoxi-2c-ld-24151-b_es\/","url":"https:\/\/www.decolor.com\/pt\/ficha-de-seguridad\/24151_deco-epoxi-2c-ld-24151-b_es\/","name":"24151_DECO-EPOXI 2C LD 24151 (B)_ES - Decolor","isPartOf":{"@id":"https:\/\/www.decolor.com\/it\/#website"},"datePublished":"2025-07-08T08:01:36+00:00","breadcrumb":{"@id":"https:\/\/www.decolor.com\/pt\/ficha-de-seguridad\/24151_deco-epoxi-2c-ld-24151-b_es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.decolor.com\/pt\/ficha-de-seguridad\/24151_deco-epoxi-2c-ld-24151-b_es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.decolor.com\/pt\/ficha-de-seguridad\/24151_deco-epoxi-2c-ld-24151-b_es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.decolor.com\/"},{"@type":"ListItem","position":2,"name":"Fichas de Seguridad","item":"https:\/\/www.decolor.com\/es\/fichas-de-seguridad\/"},{"@type":"ListItem","position":3,"name":"24151_DECO-EPOXI 2C LD 24151 (B)_ES"}]},{"@type":"WebSite","@id":"https:\/\/www.decolor.com\/it\/#website","url":"https:\/\/www.decolor.com\/it\/","name":"Decolor","description":"Web Decolor","publisher":{"@id":"https:\/\/www.decolor.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.decolor.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.decolor.com\/it\/#organization","name":"Decolor","url":"https:\/\/www.decolor.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png","contentUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png","width":1588,"height":421,"caption":"Decolor"},"image":{"@id":"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/ficha-de-seguridad\/151120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/ficha-de-seguridad"}],"about":[{"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/types\/ficha-de-seguridad"}],"wp:attachment":[{"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/media?parent=151120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}