{"id":148479,"date":"2024-07-15T10:38:59","date_gmt":"2024-07-15T10:38:59","guid":{"rendered":"https:\/\/www.decolor.com\/?p=148479"},"modified":"2024-09-05T09:31:06","modified_gmt":"2024-09-05T09:31:06","slug":"cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor","status":"publish","type":"post","link":"https:\/\/www.decolor.com\/es\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/","title":{"rendered":"Cuatro d\u00e9cadas de innovaci\u00f3n y calidad en el Cat\u00e1logo de Pinturas DECOLOR"},"content":{"rendered":"\n<p>Este a\u00f1o es especial para Pinturas DECOLOR, celebramos 40 a\u00f1os de dedicaci\u00f3n, innovaci\u00f3n y excelencia en el sector de la pintura, cuatro d\u00e9cadas de pasi\u00f3n y continua evoluci\u00f3n que garantizan, a profesionales y distribuidores de pintura, soluciones de alta calidad en sus proyectos, a trav\u00e9s de un <a href=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/03\/Cat_Decolor_ESP_2024_ED_01.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">completo Cat\u00e1logo <\/a>que refleja nuestro compromiso constante con la calidad y la satisfacci\u00f3n del cliente.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Desde 1984, hemos evolucionado constantemente, adapt\u00e1ndonos a las necesidades del mercado, hasta convertir a Pinturas DECOLOR en uno de los fabricantes que ofrece una de las mayores gamas de productos de la m\u00e1s alta calidad en el sector de la pintura<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Nuestra trayectoria ha sido un testimonio de nuestra pasi\u00f3n y compromiso con la excelencia en cada paso del camino y, en este art\u00edculo, compartimos una breve pincelada de la evoluci\u00f3n de nuestros productos a lo largo de estas cuatro d\u00e9cadas, que han sido la piedra angular de nuestro \u00e9xito y crecimiento.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Nuestra camino comenz\u00f3 en 1984 con productos esenciales como fueron: <strong>Mate Industrial, Mate Extra y Satinado Especial.<\/strong> Estos productos fueron dise\u00f1ados para satisfacer las necesidades b\u00e1sicas de nuestros clientes, ofreci\u00e9ndoles soluciones de confianza para una variedad de aplicaciones, y tuvieron una aceptaci\u00f3n tan positiva, que sentaron las bases de nuestra marca por ofrecer soluciones de alta calidad y rendimiento.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Pronto identificamos una creciente demanda de soluciones espec\u00edficas para exteriores, en respuesta al mercado introdujimos el <strong>Revestimiento especial de Fachadas<\/strong>, un producto que r\u00e1pidamente gan\u00f3 popularidad por su durabilidad y resistencia clim\u00e1tica para exteriores.<\/p>\n\n\n\n<p>Esta incorporaci\u00f3n marc\u00f3 el comienzo de nuestra expansi\u00f3n en el \u00e1mbito de las soluciones para exteriores, consolidando nuestra marca como fabricante de productos de pintura a nivel nacional.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-center\" style=\"grid-template-columns:auto 40%\"><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading has-normal-font-size\"><strong> PRODUCTOS DIFERENCIADORES <\/strong><\/h2>\n\n\n\n<p>A medida que nuestra experiencia y conocimiento del mercado crecieron, identificamos la necesidad de diversificar nuestro cat\u00e1logo, apareciendo los dos productos m\u00e1s ic\u00f3nicos al ser los primeros en tener nombre propio y que simbolizaron un gran cambio hacia la creaci\u00f3n de productos diferenciadores, fueron <strong>Decortex y Decoelast, <\/strong>productos que no solo cumpl\u00edan con las expectativas funcionales, sino que tambi\u00e9n ofrec\u00edan soluciones est\u00e9ticas excepcionales.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-8-from-Art-Magazine-Mockups-1024x683.jpg\" alt=\"\" class=\"wp-image-148487 size-full\" srcset=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-8-from-Art-Magazine-Mockups-1024x683.jpg 1024w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-8-from-Art-Magazine-Mockups-300x200.jpg 300w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-8-from-Art-Magazine-Mockups-768x512.jpg 768w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-8-from-Art-Magazine-Mockups-1536x1024.jpg 1536w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-8-from-Art-Magazine-Mockups-2048x1366.jpg 2048w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-8-from-Art-Magazine-Mockups-18x12.jpg 18w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-8-from-Art-Magazine-Mockups-1568x1045.jpg 1568w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:39% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-9-from-Art-Magazine-Mockups-1024x683.jpg\" alt=\"\" class=\"wp-image-148484 size-full\" srcset=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-9-from-Art-Magazine-Mockups-1024x683.jpg 1024w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-9-from-Art-Magazine-Mockups-300x200.jpg 300w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-9-from-Art-Magazine-Mockups-768x512.jpg 768w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-9-from-Art-Magazine-Mockups-1536x1024.jpg 1536w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-9-from-Art-Magazine-Mockups-2048x1366.jpg 2048w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-9-from-Art-Magazine-Mockups-18x12.jpg 18w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/My-mockup-9-from-Art-Magazine-Mockups-1568x1045.jpg 1568w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading has-normal-font-size\"><strong>EXPANSI\u00d3N Y SERVICIO INTEGRAL AL PROFESIONAL  Y DISTRIBUIDOR DE LA PINTURA <\/strong><\/h2>\n\n\n\n<p>El \u00e9xito de estos productos nos impuls\u00f3 a seguir expandiendo y diversificando nuestro portafolio de productos, desarrollando un Cat\u00e1logo que pudiera satisfacer todas las necesidades del profesional de la pintura; desde entonces, hemos trabajado para ampliar paulatinamente nuestra gama de productos, incorporando innovaciones tecnol\u00f3gicas y atendiendo  a infinidad de necesidades espec\u00edficas de nuestros clientes.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\"><strong>Actualmente, es un orgullo para Pinturas DECOLOR contar con uno de los cat\u00e1logos m\u00e1s amplios y completos del sector, <\/strong>abarcando desde pinturas especializadas para interiores y exteriores, soluciones t\u00e9cnicas avanzadas para aplicaciones industriales, hasta productos decorativos de alta gama.<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-background has-text-align-center wp-element-button\" href=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/03\/Cat_Decolor_ESP_2024_ED_01.pdf\" style=\"border-radius:0px;background-color:#f6b333\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>VER CAT\u00c1LOGO<\/strong> espa\u00f1ol<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-background has-text-align-center wp-element-button\" href=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/03\/Cat_Decolor_FR_2024_ED_01.pdf\" style=\"border-radius:0px;background-color:#f6b333\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>VOIR CATALOGUE<\/strong> franc\u00e9s<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-background has-text-align-center wp-element-button\" href=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/03\/Cat_Decolor_ENG_2024_ED_01.pdf\" style=\"border-radius:0px;background-color:#f6b333\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>SEE CATALOGUE<\/strong> ingl\u00e9s<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>A lo largo de estos 40 a\u00f1os, nuestro compromiso con la calidad y la innovaci\u00f3n ha sido el motor de crecimiento de Pinturas DECOLOR y nuestro objetivo sigue siendo el mismo, escuchar las necesidades de nuestros clientes, invertir en investigaci\u00f3n y desarrollo, y ofrecer a nuestros clientes soluciones que combinen funcionalidad, durabilidad y est\u00e9tica, manteniendo la satisfacci\u00f3n de nuestros clientes como nuestra m\u00e1xima prioridad.<\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En la celebraci\u00f3n de nuestro 40 Aniversario, en Pinturas DECOLOR miramos hacia el futuro con optimismo y con el compromiso de continuar creciendo con la excelencia e innovaci\u00f3n para continuar ofreciendo a profesionales y distribuidores del sector de la pintura una amplia gama de productos de alta calidad, garantizando que sus proyectos sean siempre un \u00e9xito. \u00a1Esto pinta bien!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este a\u00f1o es especial para Pinturas DECOLOR, celebramos 40 a\u00f1os de dedicaci\u00f3n, innovaci\u00f3n y excelencia en el sector de la pintura, cuatro d\u00e9cadas de pasi\u00f3n y continua evoluci\u00f3n que garantizan, a profesionales y distribuidores de pintura, soluciones de alta calidad en sus proyectos, a trav\u00e9s de un completo Cat\u00e1logo que refleja nuestro compromiso constante con&hellip; <a class=\"more-link\" href=\"https:\/\/www.decolor.com\/es\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/\">Seguir leyendo <span class=\"screen-reader-text\">Cuatro d\u00e9cadas de innovaci\u00f3n y calidad en el Cat\u00e1logo de Pinturas DECOLOR<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":148480,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-148479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-decolor","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cat\u00e1logo de Pinturas DECOLOR<\/title>\n<meta name=\"description\" content=\"En Pinturas DECOLOR innovamos para ofrecer a profesionales y distribuidores productos de la m\u00e1s alta calidad\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.decolor.com\/es\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cat\u00e1logo de Pinturas DECOLOR\" \/>\n<meta property=\"og:description\" content=\"En Pinturas DECOLOR innovamos para ofrecer a profesionales y distribuidores productos de la m\u00e1s alta calidad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.decolor.com\/es\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/\" \/>\n<meta property=\"og:site_name\" content=\"Decolor\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-15T10:38:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-05T09:31:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/Catalogo-DECOLOR-BLOG.png\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/Catalogo-DECOLOR-BLOG.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/person\/97caf6fe02baef67513e86a4f3dc9c90\"},\"headline\":\"Cuatro d\u00e9cadas de innovaci\u00f3n y calidad en el Cat\u00e1logo de Pinturas DECOLOR\",\"datePublished\":\"2024-07-15T10:38:59+00:00\",\"dateModified\":\"2024-09-05T09:31:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/\"},\"wordCount\":638,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.decolor.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/Catalogo-DECOLOR-BLOG.png\",\"articleSection\":[\"Decolor\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/\",\"url\":\"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/\",\"name\":\"Cat\u00e1logo de Pinturas DECOLOR\",\"isPartOf\":{\"@id\":\"https:\/\/www.decolor.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/Catalogo-DECOLOR-BLOG.png\",\"datePublished\":\"2024-07-15T10:38:59+00:00\",\"dateModified\":\"2024-09-05T09:31:06+00:00\",\"description\":\"En Pinturas DECOLOR innovamos para ofrecer a profesionales y distribuidores productos de la m\u00e1s alta calidad\",\"breadcrumb\":{\"@id\":\"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#primaryimage\",\"url\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/Catalogo-DECOLOR-BLOG.png\",\"contentUrl\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/Catalogo-DECOLOR-BLOG.png\",\"width\":920,\"height\":600,\"caption\":\"Cuatro d\u00e9cadas de innovaci\u00f3n y calidad en el cat\u00e1logo de Pinturas DECOLOR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.decolor.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuatro d\u00e9cadas de innovaci\u00f3n y calidad en el Cat\u00e1logo de Pinturas DECOLOR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.decolor.com\/it\/#website\",\"url\":\"https:\/\/www.decolor.com\/it\/\",\"name\":\"Decolor\",\"description\":\"Web Decolor\",\"publisher\":{\"@id\":\"https:\/\/www.decolor.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.decolor.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.decolor.com\/it\/#organization\",\"name\":\"Decolor\",\"url\":\"https:\/\/www.decolor.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png\",\"contentUrl\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png\",\"width\":1588,\"height\":421,\"caption\":\"Decolor\"},\"image\":{\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/person\/97caf6fe02baef67513e86a4f3dc9c90\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/abe407930cb2e3e5c2930411ee6911c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/abe407930cb2e3e5c2930411ee6911c6?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.decolor.com\/es\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cat\u00e1logo de Pinturas DECOLOR","description":"En Pinturas DECOLOR innovamos para ofrecer a profesionales y distribuidores productos de la m\u00e1s alta calidad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.decolor.com\/es\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/","og_locale":"es_ES","og_type":"article","og_title":"Cat\u00e1logo de Pinturas DECOLOR","og_description":"En Pinturas DECOLOR innovamos para ofrecer a profesionales y distribuidores productos de la m\u00e1s alta calidad","og_url":"https:\/\/www.decolor.com\/es\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/","og_site_name":"Decolor","article_published_time":"2024-07-15T10:38:59+00:00","article_modified_time":"2024-09-05T09:31:06+00:00","og_image":[{"width":920,"height":600,"url":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/Catalogo-DECOLOR-BLOG.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/Catalogo-DECOLOR-BLOG.png","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#article","isPartOf":{"@id":"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/"},"author":{"name":"admin","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/person\/97caf6fe02baef67513e86a4f3dc9c90"},"headline":"Cuatro d\u00e9cadas de innovaci\u00f3n y calidad en el Cat\u00e1logo de Pinturas DECOLOR","datePublished":"2024-07-15T10:38:59+00:00","dateModified":"2024-09-05T09:31:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/"},"wordCount":638,"commentCount":0,"publisher":{"@id":"https:\/\/www.decolor.com\/it\/#organization"},"image":{"@id":"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/Catalogo-DECOLOR-BLOG.png","articleSection":["Decolor"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/","url":"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/","name":"Cat\u00e1logo de Pinturas DECOLOR","isPartOf":{"@id":"https:\/\/www.decolor.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#primaryimage"},"image":{"@id":"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/Catalogo-DECOLOR-BLOG.png","datePublished":"2024-07-15T10:38:59+00:00","dateModified":"2024-09-05T09:31:06+00:00","description":"En Pinturas DECOLOR innovamos para ofrecer a profesionales y distribuidores productos de la m\u00e1s alta calidad","breadcrumb":{"@id":"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#primaryimage","url":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/Catalogo-DECOLOR-BLOG.png","contentUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/Catalogo-DECOLOR-BLOG.png","width":920,"height":600,"caption":"Cuatro d\u00e9cadas de innovaci\u00f3n y calidad en el cat\u00e1logo de Pinturas DECOLOR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.decolor.com\/de\/2024\/07\/15\/cuatro-decadas-de-innovacion-y-calidad-en-el-catalogo-de-pinturas-decolor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.decolor.com\/"},{"@type":"ListItem","position":2,"name":"Cuatro d\u00e9cadas de innovaci\u00f3n y calidad en el Cat\u00e1logo de Pinturas DECOLOR"}]},{"@type":"WebSite","@id":"https:\/\/www.decolor.com\/it\/#website","url":"https:\/\/www.decolor.com\/it\/","name":"Decolor","description":"Web Decolor","publisher":{"@id":"https:\/\/www.decolor.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.decolor.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.decolor.com\/it\/#organization","name":"Decolor","url":"https:\/\/www.decolor.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png","contentUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png","width":1588,"height":421,"caption":"Decolor"},"image":{"@id":"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/person\/97caf6fe02baef67513e86a4f3dc9c90","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/abe407930cb2e3e5c2930411ee6911c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/abe407930cb2e3e5c2930411ee6911c6?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.decolor.com\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/posts\/148479"}],"collection":[{"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/comments?post=148479"}],"version-history":[{"count":17,"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/posts\/148479\/revisions"}],"predecessor-version":[{"id":148507,"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/posts\/148479\/revisions\/148507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/media\/148480"}],"wp:attachment":[{"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/media?parent=148479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/categories?post=148479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.decolor.com\/es\/wp-json\/wp\/v2\/tags?post=148479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}