{"id":148625,"date":"2024-07-24T11:08:33","date_gmt":"2024-07-24T11:08:33","guid":{"rendered":"https:\/\/www.decolor.com\/?p=148625"},"modified":"2024-09-05T09:35:05","modified_gmt":"2024-09-05T09:35:05","slug":"deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos","status":"publish","type":"post","link":"https:\/\/www.decolor.com\/it\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/","title":{"rendered":"DECO-EPOXI AQUA monocomponente, rivoluzione nei rivestimenti per pavimenti"},"content":{"rendered":"<p><\/p>\n\n\n\n<p>Nel dinamico mondo delle vernici e dei rivestimenti, efficienza e durata sono fondamentali per il successo di qualsiasi progetto, <strong>DECO-EPOXY AQUA 1 C PRECATALIZZATO<\/strong>, con la sua tecnologia ibrida acrilico-epossidica a base acqua, lo rende un prodotto che <strong>ha ridefinito gli standard per le pavimentazioni continue grazie alla sua tecnologia innovativa e alla sua versatilit\u00e0.<\/strong><\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>DECO EPOXI AQUA MONOCOMPONENTE \u00e8 una soluzione evoluta che unisce la semplicit\u00e0 di utilizzo, non dovendo realizzare impasti, con prestazioni eccezionali, sia in interno che in esterno, paragonabili ai tradizionali sistemi epossidici bicomponenti, ma con ulteriori vantaggi che lo rendono unico e lo rendono un&#039;opzione ideale per progetti che richiedono efficienza e risultati immediati.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>DECO-EPOXI AQUA 1 componente PRECATALIZZATO \u00e8 ora presentato in un packaging rinnovato, che incorpora il nuovo logo Pinturas DECOLOR, un cambiamento che non rappresenta solo un aggiornamento visivo, ma anche il nostro continuo impegno per l&#039;innovazione, la qualit\u00e0 e la sostenibilit\u00e0, per offrire il il miglior servizio ai professionisti e ai distributori della pittura.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\"><strong>Cosa rende speciale il DECO-EPOXI AQUA 1C PRECATALIZZATO?<\/strong><\/h2>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>DECO EPOXI ONE COMPONENT \u00e8 progettato per un&#039;ampia gamma di applicazioni in spazi commerciali e residenziali, sia interni che esterni, che richiedono una combinazione di durabilit\u00e0 e appeal visivo, inoltre:<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>PRONTO ALL&#039;USO: <\/strong>Senza la necessit\u00e0 di realizzare miscele complicate, il rivestimento DECO EPOXI AQUA 1C arriva preparato per essere applicato direttamente, risparmiando tempo e riducendo la possibilit\u00e0 di errori durante l&#039;applicazione.<\/li>\n\n\n\n<li><strong>APPLICAZIONI INTERNE ED ESTERNE<\/strong>: La sua formula avanzata consente un&#039;applicazione efficiente e duratura sia all&#039;interno che all&#039;esterno, fornendo un&#039;ottima protezione e una finitura pulita in una variet\u00e0 di condizioni ambientali impegnative, rendendolo una scelta perfetta indipendentemente dall&#039;ambiente.<\/li>\n\n\n\n<li><strong>RITORNO VELOCE IN SERVIZIO:<\/strong> La sua applicazione riduce al minimo i tempi di inattivit\u00e0 del supporto verniciato, perch\u00e9 uno dei suoi vantaggi \u00e8 il rapido tempo di indurimento, consentendo alle superfici trattate di essere nuovamente operative in tempi ridotti.<\/li>\n\n\n\n<li><strong>ALTA DURATA: <\/strong>Fornisce una protezione di lunga durata per le superfici trattate, garantendo che mantengano la loro integrit\u00e0 e il loro aspetto molto pi\u00f9 a lungo.<\/li>\n\n\n\n<li><strong>RESISTENZA CHIMICA E MECCANICA:<\/strong> Formando una pellicola dura, impermeabile ed elastica, fornisce un&#039;elevata protezione per resistere all&#039;esposizione a prodotti chimici aggressivi come acidi, alcali e oli, oltre ad offrire un&#039;elevata resistenza all&#039;abrasione e all&#039;usura ai pneumatici in climi freddi e caldi, offrendo una lunga durata vita utile pi\u00f9 lunga.<\/li>\n\n\n\n<li><strong>OTTIMA ADERENZA<\/strong>: Aderisce bene purch\u00e9 la superficie sia ben preparata Per fare ci\u00f2, prima di iniziare il processo applicativo del DECO EPOXI monocomponente, \u00e8 necessario seguire alcune istruzioni per garantire l&#039;ottenimento dei migliori risultati nell&#039;applicazione:\n<ul class=\"wp-block-list\">\n<li><strong>Applicazione su cemento, calcestruzzo: <\/strong>Il calcestruzzo dovr\u00e0 essere preventivamente fatto presa, per cui dovr\u00e0 essere trascorso 1 mese dalla sua applicazione. La superficie deve avere un&#039;adeguata rugosit\u00e0 e si consiglia di prepararla mediante levigatrice con pietra diamantata (o altri dischi abrasivi) o granigliatrice. Trattare la superficie con salfum\u00e1n (acido cloridrico) diluito 10 \u2013 15% per neutralizzare l&#039;alcalinit\u00e0 del cemento. Poi lavate e lasciate asciugare. Applicare come primer per pavimenti <a href=\"https:\/\/www.decolor.com\/it\/producto\/decokril-rapid\/\" target=\"_blank\" rel=\"noreferrer noopener\">DECOKRIL RAPIDO<\/a> delle vernici DECOLOR. Dopo 24 ore applicare gli strati successivi di DECO-EPOXI AQUA 1C, diluendo al massimo 5% con acqua. Le vecchie superfici devono essere spazzolate energicamente per pulirle, eliminando completamente grasso e polvere, nonch\u00e9 ogni altra contaminazione superficiale.<\/li>\n\n\n\n<li><strong>Applicazione su superfici metalliche:<\/strong> Le zone arrugginite dovranno essere rimosse mediante spazzolatura manuale o meccanica, quindi applicare 2 mani di AQUA ANTICORROSIVE EPOXY PRIMER oppure <a href=\"https:\/\/www.decolor.com\/it\/producto\/imprimacion-polivalente-aqua\/\" target=\"_blank\" rel=\"noreferrer noopener\">PRIMER VERSATILE ACQUA<\/a> delle Vernici DECOLOR prima di procedere con la verniciatura. Applicare le mani successive diluendo 5-10% con acqua.<\/li>\n\n\n\n<li><strong>Applicazione su intonaco, legno: <\/strong>Stampa con <a href=\"https:\/\/www.decolor.com\/it\/producto\/selladora-aqua\/\" target=\"_blank\" rel=\"noreferrer noopener\">SIGILLANTE ACQUA<\/a> delle vernici DECOLOR. Applicare le mani successive diluendo 5-10% con acqua.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>IN QUALSIASI COLORE:<\/strong> Permette di personalizzare i progetti potendo realizzare qualsiasi colore con le basi P \u2013 TR<\/li>\n\n\n\n<li><strong>RESISTENZA AI RAGGI UV:<\/strong> Protegge dai danni del sole, prevenendo lo scolorimento e il deterioramento prematuro.<\/li>\n\n\n\n<li><strong>BASSO CONTENUTO DI COV:<\/strong> Un rivestimento pi\u00f9 sicuro per l&#039;ambiente e per la salute di chi lo applica, con una formula che riduce l&#039;emissione di composti organici volatili.<\/li>\n\n\n\n<li><strong>VERSATILIT\u00c0 DELLE APPLICAZIONI:<\/strong> Adatto ad un&#039;ampia gamma di applicazioni e superfici impegnative, DECO-EPOXI AQUA 1 C si adatta a diverse esigenze e ambienti.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\"><strong>Applicazioni di DECO-EPOXI AQUA ONE COMPONENT<\/strong><\/h2>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>DECO-EPOXY AQUA monocomponente PRECATALIZZATO<\/strong> che pu\u00f2 essere applicato su un gran numero di tipologie di superfici, offrendo una facile applicazione e una manutenzione semplice e veloce, che lo rendono un prodotto essenziale per i professionisti e i distributori di vernici. Di seguito riportiamo in dettaglio alcuni dei luoghi in cui il suo utilizzo \u00e8 pi\u00f9 frequente e consigliato:<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Soluzioni in ambito sanitario e alimentare: <\/strong>Nei luoghi in cui l&#039;igiene \u00e8 fondamentale, come ad esempio <strong>ospedali, cliniche e laboratori,<\/strong> DECO-EPOXI AQUA monocomponente offre una superficie facilmente disinfettabile e resistente agli agenti chimici. La sua applicazione \u00e8 perfetta anche nelle aziende alimentari e nelle cucine dei ristoranti, dove resistenza chimica e facilit\u00e0 di pulizia sono fondamentali per soddisfare i pi\u00f9 esigenti standard di pulizia e sicurezza.<\/li>\n\n\n\n<li><strong>Protezione e durata:<\/strong> La resistenza di DECO-EPOXI AQUA 1C ai liquidi aggressivi e corrosivi lo rende un&#039;opzione affidabile per laboratori e magazzini, cos\u00ec come nelle piccole aziende alimentari esposte a sversamenti, fornendo protezione e durata eccellenti, garantendo un ambiente sicuro e funzionale.<\/li>\n\n\n\n<li><strong>Estetica pulita e funzionalit\u00e0: <\/strong>La combinazione di durabilit\u00e0 e aspetto pulito fornita da un pavimento in resina epossidica ne ha favorito l&#039;utilizzo nelle PMI, nei punti di ricarica delle auto elettriche, offrendo un aspetto pulito e moderno che contribuisce a dare all&#039;ambiente un&#039;immagine professionale e ordinata.<\/li>\n\n\n\n<li><strong>Uso decorativo: <\/strong>DECO-EPOXI AQUA monocomponente viene utilizzato anche come rivestimento decorativo per il suo aspetto gradevole, che insieme alle propriet\u00e0 funzionali lo rendono <strong>perfetto per uffici, locali commerciali, abitazioni, bordi piscina, ecc.,<\/strong> dove cerchiamo di coniugare estetica e resistenza per creare spazi visivamente piacevoli e tenaci per l&#039;uso quotidiano.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>DECO-EPOXI AQUA 1 Component PRE-CATALIZZATO \u00e8 progettato come un&#039;opzione accessibile e di alta qualit\u00e0 per progetti su piccola scala, combinando durabilit\u00e0 e semplicit\u00e0 nella sua applicazione, motivo per cui \u00e8 perfetto per progetti di piccole imprese e individui che cercano un prodotto efficiente e facile da utilizzo, non richiedono le complessit\u00e0 associate ai sistemi epossidici bicomponenti.<\/strong><\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Ma noi di Pinturas DECOLOR sappiamo che le esigenze non sono tutte uguali e variano notevolmente, per questo offriamo una gamma completa di <a href=\"https:\/\/www.decolor.com\/it\/pintura-suelo\/\" target=\"_blank\" rel=\"noreferrer noopener\">soluzioni per pavimentazioni e impianti sportivi,<\/a> che includono prodotti bicomponenti progettati per soddisfare richieste industriali, aziendali, sanitarie e commerciali molto pi\u00f9 complesse ed esigenti, quindi i nostri prodotti coprono tutti i livelli di requisiti, dalle applicazioni semplici a quelle pi\u00f9 impegnative, garantendo la giusta opzione per ogni progetto.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La combinazione di innovazione tecnologica e facilit\u00e0 d&#039;uso rendono DECO-EPOXI AQUA 1 Component PRECATALIZZATO l&#039;opzione perfetta per i professionisti della verniciatura e i distributori che cercano soluzioni efficienti, durevoli e adattabili a molteplici applicazioni, semplificando il processo applicativo.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Noi di Pinturas DECOLOR comprendiamo che ogni progetto di pavimentazione ha le proprie esigenze e sfide, ecco perch\u00e9 offriamo una gamma completa di rivestimenti, da <strong>DECO-EPOXY AQUA 1 Componente PRECATALIZZATO<\/strong> per applicazioni pi\u00f9 accessibili rispetto a molti altri prodotti per esigenze e ambienti pi\u00f9 esigenti. Se hai bisogno di una consulenza personalizzata, ti aiutiamo a selezionare il prodotto giusto per le tue esigenze specifiche. <\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/www.decolor.com\/it\/contacto\/\" style=\"background-color:#f6b333\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>+INFORMAZIONI<\/strong><\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nel dinamico mondo delle vernici e dei rivestimenti, efficienza e durata sono fondamentali per il successo di qualsiasi progetto, DECO-EPOXI AQUA 1 C PRECATALIZZATO, con la sua tecnologia ibrida acrilico-epossidica a base acqua, ne fa un prodotto che ha ridefinito il concetto di standard delle pavimentazioni continue grazie alla sua\u2026 <a class=\"more-link\" href=\"https:\/\/www.decolor.com\/it\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/\">continua a leggere <span class=\"screen-reader-text\">DECO-EPOXI AQUA monocomponente, rivoluzione nei rivestimenti per pavimenti<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":148640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-148625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-decolor","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DECO-EPOXI AQUA - Evoluci\u00f3n en recubrimiento<\/title>\n<meta name=\"description\" content=\"Producto DECO-EPOXI AQUA recubrimientos de suelos continuos gracias a su innovadora tecnolog\u00eda y versatilidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.decolor.com\/it\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DECO-EPOXI AQUA - Evoluci\u00f3n en recubrimiento\" \/>\n<meta property=\"og:description\" content=\"Producto DECO-EPOXI AQUA recubrimientos de suelos continuos gracias a su innovadora tecnolog\u00eda y versatilidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.decolor.com\/it\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/\" \/>\n<meta property=\"og:site_name\" content=\"Decolor\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-24T11:08:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-05T09:35:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/DECO-EPOXI-1C-MONOCOMPONENTE-Pinturas-DECOLOR.png\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/person\/97caf6fe02baef67513e86a4f3dc9c90\"},\"headline\":\"DECO-EPOXI AQUA monocomponente, revoluci\u00f3n en recubrimientos de suelos\",\"datePublished\":\"2024-07-24T11:08:33+00:00\",\"dateModified\":\"2024-09-05T09:35:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/\"},\"wordCount\":1334,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.decolor.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/DECO-EPOXI-1C-MONOCOMPONENTE-Pinturas-DECOLOR.png\",\"articleSection\":[\"Decolor\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/\",\"url\":\"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/\",\"name\":\"DECO-EPOXI AQUA - Evoluci\u00f3n en recubrimiento\",\"isPartOf\":{\"@id\":\"https:\/\/www.decolor.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/DECO-EPOXI-1C-MONOCOMPONENTE-Pinturas-DECOLOR.png\",\"datePublished\":\"2024-07-24T11:08:33+00:00\",\"dateModified\":\"2024-09-05T09:35:05+00:00\",\"description\":\"Producto DECO-EPOXI AQUA recubrimientos de suelos continuos gracias a su innovadora tecnolog\u00eda y versatilidad.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#primaryimage\",\"url\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/DECO-EPOXI-1C-MONOCOMPONENTE-Pinturas-DECOLOR.png\",\"contentUrl\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/DECO-EPOXI-1C-MONOCOMPONENTE-Pinturas-DECOLOR.png\",\"width\":920,\"height\":600,\"caption\":\"Pintura para suelos EPOXI monocomponente\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.decolor.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DECO-EPOXI AQUA monocomponente, revoluci\u00f3n en recubrimientos de suelos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.decolor.com\/it\/#website\",\"url\":\"https:\/\/www.decolor.com\/it\/\",\"name\":\"Decolor\",\"description\":\"Web Decolor\",\"publisher\":{\"@id\":\"https:\/\/www.decolor.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.decolor.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.decolor.com\/it\/#organization\",\"name\":\"Decolor\",\"url\":\"https:\/\/www.decolor.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png\",\"contentUrl\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png\",\"width\":1588,\"height\":421,\"caption\":\"Decolor\"},\"image\":{\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/person\/97caf6fe02baef67513e86a4f3dc9c90\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/abe407930cb2e3e5c2930411ee6911c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/abe407930cb2e3e5c2930411ee6911c6?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.decolor.com\/it\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DECO-EPOXI AQUA - Evoluci\u00f3n en recubrimiento","description":"Producto DECO-EPOXI AQUA recubrimientos de suelos continuos gracias a su innovadora tecnolog\u00eda y versatilidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.decolor.com\/it\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/","og_locale":"it_IT","og_type":"article","og_title":"DECO-EPOXI AQUA - Evoluci\u00f3n en recubrimiento","og_description":"Producto DECO-EPOXI AQUA recubrimientos de suelos continuos gracias a su innovadora tecnolog\u00eda y versatilidad.","og_url":"https:\/\/www.decolor.com\/it\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/","og_site_name":"Decolor","article_published_time":"2024-07-24T11:08:33+00:00","article_modified_time":"2024-09-05T09:35:05+00:00","og_image":[{"width":920,"height":600,"url":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/DECO-EPOXI-1C-MONOCOMPONENTE-Pinturas-DECOLOR.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#article","isPartOf":{"@id":"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/"},"author":{"name":"admin","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/person\/97caf6fe02baef67513e86a4f3dc9c90"},"headline":"DECO-EPOXI AQUA monocomponente, revoluci\u00f3n en recubrimientos de suelos","datePublished":"2024-07-24T11:08:33+00:00","dateModified":"2024-09-05T09:35:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/"},"wordCount":1334,"commentCount":0,"publisher":{"@id":"https:\/\/www.decolor.com\/it\/#organization"},"image":{"@id":"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/DECO-EPOXI-1C-MONOCOMPONENTE-Pinturas-DECOLOR.png","articleSection":["Decolor"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/","url":"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/","name":"DECO-EPOXI AQUA - Evoluci\u00f3n en recubrimiento","isPartOf":{"@id":"https:\/\/www.decolor.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#primaryimage"},"image":{"@id":"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/DECO-EPOXI-1C-MONOCOMPONENTE-Pinturas-DECOLOR.png","datePublished":"2024-07-24T11:08:33+00:00","dateModified":"2024-09-05T09:35:05+00:00","description":"Producto DECO-EPOXI AQUA recubrimientos de suelos continuos gracias a su innovadora tecnolog\u00eda y versatilidad.","breadcrumb":{"@id":"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#primaryimage","url":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/DECO-EPOXI-1C-MONOCOMPONENTE-Pinturas-DECOLOR.png","contentUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/07\/DECO-EPOXI-1C-MONOCOMPONENTE-Pinturas-DECOLOR.png","width":920,"height":600,"caption":"Pintura para suelos EPOXI monocomponente"},{"@type":"BreadcrumbList","@id":"https:\/\/www.decolor.com\/en\/2024\/07\/24\/deco-epoxi-aqua-monocomponente-revolucion-en-recubrimientos-de-suelos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.decolor.com\/"},{"@type":"ListItem","position":2,"name":"DECO-EPOXI AQUA monocomponente, revoluci\u00f3n en recubrimientos de suelos"}]},{"@type":"WebSite","@id":"https:\/\/www.decolor.com\/it\/#website","url":"https:\/\/www.decolor.com\/it\/","name":"Colore","description":"Decorazione web","publisher":{"@id":"https:\/\/www.decolor.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.decolor.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.decolor.com\/it\/#organization","name":"Colore","url":"https:\/\/www.decolor.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png","contentUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png","width":1588,"height":421,"caption":"Decolor"},"image":{"@id":"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/person\/97caf6fe02baef67513e86a4f3dc9c90","name":"amministratore","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/abe407930cb2e3e5c2930411ee6911c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/abe407930cb2e3e5c2930411ee6911c6?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.decolor.com\/it\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.decolor.com\/it\/wp-json\/wp\/v2\/posts\/148625"}],"collection":[{"href":"https:\/\/www.decolor.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.decolor.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.decolor.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.decolor.com\/it\/wp-json\/wp\/v2\/comments?post=148625"}],"version-history":[{"count":10,"href":"https:\/\/www.decolor.com\/it\/wp-json\/wp\/v2\/posts\/148625\/revisions"}],"predecessor-version":[{"id":148647,"href":"https:\/\/www.decolor.com\/it\/wp-json\/wp\/v2\/posts\/148625\/revisions\/148647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.decolor.com\/it\/wp-json\/wp\/v2\/media\/148640"}],"wp:attachment":[{"href":"https:\/\/www.decolor.com\/it\/wp-json\/wp\/v2\/media?parent=148625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.decolor.com\/it\/wp-json\/wp\/v2\/categories?post=148625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.decolor.com\/it\/wp-json\/wp\/v2\/tags?post=148625"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}