{"id":143771,"date":"2024-02-21T08:26:06","date_gmt":"2024-02-21T08:26:06","guid":{"rendered":"https:\/\/decolor.es\/?post_type=ficha-de-seguridad&#038;p=143771"},"modified":"2024-02-21T08:26:06","modified_gmt":"2024-02-21T08:26:06","slug":"13690_decokril-anclaje_es-pdf","status":"publish","type":"ficha-de-seguridad","link":"https:\/\/www.decolor.com\/nl\/ficha-de-seguridad\/13690_decokril-anclaje_es-pdf\/","title":{"rendered":"13690_DECOKRIL ANCLAJE_EN.pdf"},"template":"","class_list":["post-143771","ficha-de-seguridad","type-ficha-de-seguridad","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>13690_DECOKRIL ANCLAJE_ES.pdf - Decolor<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"13690_DECOKRIL ANCLAJE_ES.pdf - Decolor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.decolor.com\/nl\/ficha-de-seguridad\/13690_decokril-anclaje_es-pdf\/\" \/>\n<meta property=\"og:site_name\" content=\"Decolor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/ficha-de-seguridad\\\/13690_decokril-anclaje_es-pdf\\\/\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/ficha-de-seguridad\\\/13690_decokril-anclaje_es-pdf\\\/\",\"name\":\"13690_DECOKRIL ANCLAJE_ES.pdf - Decolor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#website\"},\"datePublished\":\"2024-02-21T08:26:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/ficha-de-seguridad\\\/13690_decokril-anclaje_es-pdf\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.decolor.com\\\/ficha-de-seguridad\\\/13690_decokril-anclaje_es-pdf\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/ficha-de-seguridad\\\/13690_decokril-anclaje_es-pdf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.decolor.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fichas de Seguridad\",\"item\":\"https:\\\/\\\/www.decolor.com\\\/es\\\/fichas-de-seguridad\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"13690_DECOKRIL ANCLAJE_ES.pdf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/\",\"name\":\"Decolor\",\"description\":\"Web Decolor\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#organization\",\"name\":\"Decolor\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/marca_principal_pinturas_decolor_color.png\",\"contentUrl\":\"https:\\\/\\\/www.decolor.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/marca_principal_pinturas_decolor_color.png\",\"width\":1588,\"height\":421,\"caption\":\"Decolor\"},\"image\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"13690_DECOKRIL ANCLAJE_ES.pdf - Ontkleuren","robots":{"index":"noindex","follow":"follow"},"og_locale":"nl_NL","og_type":"article","og_title":"13690_DECOKRIL ANCLAJE_ES.pdf - Decolor","og_url":"https:\/\/www.decolor.com\/nl\/ficha-de-seguridad\/13690_decokril-anclaje_es-pdf\/","og_site_name":"Decolor","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.decolor.com\/ficha-de-seguridad\/13690_decokril-anclaje_es-pdf\/","url":"https:\/\/www.decolor.com\/ficha-de-seguridad\/13690_decokril-anclaje_es-pdf\/","name":"13690_DECOKRIL ANCLAJE_ES.pdf - Ontkleuren","isPartOf":{"@id":"https:\/\/www.decolor.com\/it\/#website"},"datePublished":"2024-02-21T08:26:06+00:00","breadcrumb":{"@id":"https:\/\/www.decolor.com\/ficha-de-seguridad\/13690_decokril-anclaje_es-pdf\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.decolor.com\/ficha-de-seguridad\/13690_decokril-anclaje_es-pdf\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.decolor.com\/ficha-de-seguridad\/13690_decokril-anclaje_es-pdf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.decolor.com\/"},{"@type":"ListItem","position":2,"name":"Fichas de Seguridad","item":"https:\/\/www.decolor.com\/es\/fichas-de-seguridad\/"},{"@type":"ListItem","position":3,"name":"13690_DECOKRIL ANCLAJE_ES.pdf"}]},{"@type":"WebSite","@id":"https:\/\/www.decolor.com\/it\/#website","url":"https:\/\/www.decolor.com\/it\/","name":"Kleur","description":"Web ontkleuren","publisher":{"@id":"https:\/\/www.decolor.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.decolor.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.decolor.com\/it\/#organization","name":"Kleur","url":"https:\/\/www.decolor.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png","contentUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png","width":1588,"height":421,"caption":"Decolor"},"image":{"@id":"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/ficha-de-seguridad\/143771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/ficha-de-seguridad"}],"about":[{"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/types\/ficha-de-seguridad"}],"wp:attachment":[{"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/media?parent=143771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}