{"id":147944,"date":"2024-05-07T10:00:03","date_gmt":"2024-05-07T10:00:03","guid":{"rendered":"https:\/\/www.decolor.com\/?p=147944"},"modified":"2024-07-01T12:23:42","modified_gmt":"2024-07-01T12:23:42","slug":"pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos","status":"publish","type":"post","link":"https:\/\/www.decolor.com\/nl\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/","title":{"rendered":"DECOLOR Verf promoot kunst en creativiteit op het Festival of the Senses"},"content":{"rendered":"<p>Het aftellen naar het begin van de <a href=\"https:\/\/www.festivalsentidos.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">XVII editie van het Festival van de Zintuigen <\/a> de La Roda is begonnen met zijn offici\u00eble presentatie op La Roda, een evenement dat muziek, gastronomie en kunst samenbrengt in een unieke ervaring en waarin Pinturas DECOLOR, als sponsors, onze toewijding aan kunst en cultuur opnieuw bevestigt en zo bijdraagt aan de promotie en verspreiding van creativiteit en artistieke expressie in de DECOLOR Art Zone.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>De presentatie werd bijgewoond door Antonio Javier Lozano, Business Development Director van Pinturas DECOLOR, samen met lokale autoriteiten, andere sponsors, medewerkers en organisatoren, en tijdens welke de burgemeester van La Roda, Juan Ram\u00f3n Amores, verraste met de aankondiging dat het Festival van de Senses zal binnenkort het offici\u00eble nieuws ontvangen dat het door de regionale overheid is uitgeroepen tot Festival van Regionaal Toeristisch Belang, wat verder zal bijdragen aan het plaatsen van La Roda op de kaart van muziekfestivals in Spanje.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\"><strong>DECOLOR Art Zone op het Roda Senses Festival<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>De DECOLOR Art Zone is een ruimte van het Festival of the Senses, gesponsord en georganiseerd door Pinturas DECOLOR, bedoeld voor artistieke creatie waar schilderkunst, kunst en creativiteit met elkaar verweven zijn. <\/strong>op een unieke manier die enerzijds de interactie van de aanwezigen met kunst en schilderkunst zoekt, en anderzijds een platform voor de verspreiding en verspreiding van de werken van lokale kunstenaars.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>In deze editie zal dat wel het geval zijn <strong>Live Art met Rodense kunstenaar Mois\u00e9s Charco Castillo<\/strong>, die live zal schilderen, zijn talent en creativiteit zal tonen en tegelijkertijd een uniek werk zal cre\u00ebren voor bezoekers, zal op vrijdag en zaterdag vanaf 20.00 uur aanwezig zijn. om 10 uur &#039;s avonds.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Daarnaast de lokale ontwerper <strong>Ester Marse zal een interactieve installatie cre\u00ebren zodat bezoekers hun creativiteit in de praktijk kunnen brengen <\/strong>gedurende het hele festival.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Met deze activiteiten is de Decolor Art Zone bedoeld als een ruimte waar dingen gebeuren rond kunst en creativiteit, maar ook als ontmoetingspunt om tijdens het evenement \u2018revoluties te verlagen\u2019.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>De <strong>DECOLOR Kunstzone <\/strong>Het is niet alleen een showcase voor lokaal talent, maar ook een ruimte voor leren en culturele bemiddeling, waarin studenten uit de <a href=\"https:\/\/humanidadesab.uclm.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Faculteit der Geesteswetenschappen van Albacete van de Universiteit van Castilla-La Mancha (UCLM) <\/a>Zij krijgen de kans om hun kennis als culturele bemiddelaars in de praktijk te brengen en zo de ervaring van de bezoekers te verrijken.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Met elk detail, zorgvuldig georganiseerd door Pinturas DECOLOR, belooft de DECOLOR Art Zone van het Festival van de Zintuigen van La Roda een onvergetelijke ervaring te worden voor alle liefhebbers van kunst, muziek, cultuur en natuurlijk schilderkunst.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>We herinneren u eraan dat het La Roda Festival of the Senses zal plaatsvinden op 14, 15 en 16 juni en hoopt alle verwachtingen te overtreffen en een historisch bezoekersrecord te behalen.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Vanuit Pinturas DECOLOR nodigen wij u uit om met ons mee te doen en deel te nemen aan de DECOLOR Art Zone, waar u unieke werken kunt ontdekken, getuige kunt zijn van de creatie van live kunst, kunt communiceren met lokale kunstenaars en de mogelijkheid heeft om uzelf uit te drukken met schilderen, plus vele verrassingen.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;uploadedSrc&quot;:&quot;https:\\\/\\\/www.decolor.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Festival-de-los-Sentidos-Pinturas-Decolor-2.jpg&quot;,&quot;figureClassNames&quot;:&quot;wp-block-image size-large&quot;,&quot;figureStyles&quot;:null,&quot;imgClassNames&quot;:&quot;wp-image-147956&quot;,&quot;imgStyles&quot;:null,&quot;targetWidth&quot;:1600,&quot;targetHeight&quot;:1066,&quot;scaleAttr&quot;:false,&quot;ariaLabel&quot;:&quot;Vergroot afbeelding: Pinturas DECOLOR Festival de los Sentidos&quot;,&quot;alt&quot;:&quot;Pinturas DECOLOR Festival de los Sentidos&quot;}\" data-wp-interactive=\"core\/image\" class=\"wp-block-image size-large wp-lightbox-container\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" data-id=\"147956\" src=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-2-1024x682.jpg\" alt=\"Pinturas DECOLOR Festival de los Sentidos\" class=\"wp-image-147956\" srcset=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-2-1024x682.jpg 1024w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-2-300x200.jpg 300w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-2-768x512.jpg 768w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-2-1536x1023.jpg 1536w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-2-18x12.jpg 18w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-2-1568x1045.jpg 1568w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-2.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Vergroot afbeelding: DECOLOR Schilderijenfestival van de zintuigen\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on-async--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"context.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"context.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;uploadedSrc&quot;:&quot;https:\\\/\\\/www.decolor.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Festival-de-los-Sentidos-Pinturas-Decolor-1-1.jpg&quot;,&quot;figureClassNames&quot;:&quot;wp-block-image size-large&quot;,&quot;figureStyles&quot;:null,&quot;imgClassNames&quot;:&quot;wp-image-147959&quot;,&quot;imgStyles&quot;:null,&quot;targetWidth&quot;:1200,&quot;targetHeight&quot;:1376,&quot;scaleAttr&quot;:false,&quot;ariaLabel&quot;:&quot;Vergroot afbeelding: Festival de los Sentidos - Pinturas DECOLOR&quot;,&quot;alt&quot;:&quot;Festival de los Sentidos - Pinturas DECOLOR&quot;}\" data-wp-interactive=\"core\/image\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"893\" height=\"1024\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" data-id=\"147959\" src=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-1-1-893x1024.jpg\" alt=\"Festival de los Sentidos - Pinturas DECOLOR\" class=\"wp-image-147959\" srcset=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-1-1-893x1024.jpg 893w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-1-1-262x300.jpg 262w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-1-1-768x881.jpg 768w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-1-1-10x12.jpg 10w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-1-1.jpg 1200w\" sizes=\"(max-width: 893px) 100vw, 893px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Vergroot afbeelding: Festival van de zintuigen - DECOLOR Schilderijen\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on-async--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"context.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"context.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"147958\" src=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-3-1-1024x576.jpg\" alt=\"\" class=\"wp-image-147958\" srcset=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-3-1-1024x576.jpg 1024w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-3-1-300x169.jpg 300w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-3-1-768x432.jpg 768w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-3-1-1536x864.jpg 1536w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-3-1-18x10.jpg 18w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-3-1-1568x882.jpg 1568w, https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/Festival-de-los-Sentidos-Pinturas-Decolor-3-1.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-small-font-size\">Beleef met Pinturas DECOLOR een onvergetelijke ervaring vol inspiratie en plezier op het Festival of the Senses. <\/h4>\n\n\n\n<h4 class=\"wp-block-heading has-small-font-size\">Dit ziet er goed uit!<\/h4>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/www.festivalsentidos.com\/\" style=\"background-color:#f6b333\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>+INFORMATIE<\/strong><\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Het aftellen naar de start van de XVII editie van het Festival van de Zintuigen van La Roda is begonnen met de offici\u00eble presentatie in La Roda, een evenement dat muziek, gastronomie en kunst combineert in een unieke ervaring en waarin Pinturas DECOLOR, als sponsor, onze toewijding aan kunst en\u2026 <a class=\"more-link\" href=\"https:\/\/www.decolor.com\/nl\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/\">jij leest groen <span class=\"screen-reader-text\">DECOLOR Verf promoot kunst en creativiteit op het Festival of the Senses<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":147948,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-147944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-decolor","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pinturas DECOLOR en el Festival de los Sentidos<\/title>\n<meta name=\"description\" content=\"Pinturas DECOLOR impulsando el arte y la creatividad en el Festival de los Sentidos con su estaci\u00f3n para expresarse con la pintura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.decolor.com\/nl\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pinturas DECOLOR en el Festival de los Sentidos\" \/>\n<meta property=\"og:description\" content=\"Pinturas DECOLOR impulsando el arte y la creatividad en el Festival de los Sentidos con su estaci\u00f3n para expresarse con la pintura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.decolor.com\/nl\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Decolor\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-07T10:00:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-01T12:23:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/FESTIVAL-DE-LOS-SENTIDOS-Pinturas-Decolor-BLOG.png\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/FESTIVAL-DE-LOS-SENTIDOS-Pinturas-Decolor-BLOG.png\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/person\/97caf6fe02baef67513e86a4f3dc9c90\"},\"headline\":\"Pinturas DECOLOR impulsando el arte y la creatividad en el Festival de los Sentidos\",\"datePublished\":\"2024-05-07T10:00:03+00:00\",\"dateModified\":\"2024-07-01T12:23:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/\"},\"wordCount\":612,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.decolor.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/FESTIVAL-DE-LOS-SENTIDOS-Pinturas-Decolor-BLOG.png\",\"articleSection\":[\"Decolor\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/\",\"url\":\"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/\",\"name\":\"Pinturas DECOLOR en el Festival de los Sentidos\",\"isPartOf\":{\"@id\":\"https:\/\/www.decolor.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/FESTIVAL-DE-LOS-SENTIDOS-Pinturas-Decolor-BLOG.png\",\"datePublished\":\"2024-05-07T10:00:03+00:00\",\"dateModified\":\"2024-07-01T12:23:42+00:00\",\"description\":\"Pinturas DECOLOR impulsando el arte y la creatividad en el Festival de los Sentidos con su estaci\u00f3n para expresarse con la pintura.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#primaryimage\",\"url\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/FESTIVAL-DE-LOS-SENTIDOS-Pinturas-Decolor-BLOG.png\",\"contentUrl\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/FESTIVAL-DE-LOS-SENTIDOS-Pinturas-Decolor-BLOG.png\",\"width\":920,\"height\":600,\"caption\":\"Festival de los Sentidos PINTURAS DECOLOR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.decolor.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pinturas DECOLOR impulsando el arte y la creatividad en el Festival de los Sentidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.decolor.com\/it\/#website\",\"url\":\"https:\/\/www.decolor.com\/it\/\",\"name\":\"Decolor\",\"description\":\"Web Decolor\",\"publisher\":{\"@id\":\"https:\/\/www.decolor.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.decolor.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.decolor.com\/it\/#organization\",\"name\":\"Decolor\",\"url\":\"https:\/\/www.decolor.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png\",\"contentUrl\":\"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png\",\"width\":1588,\"height\":421,\"caption\":\"Decolor\"},\"image\":{\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/person\/97caf6fe02baef67513e86a4f3dc9c90\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/www.decolor.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/abe407930cb2e3e5c2930411ee6911c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/abe407930cb2e3e5c2930411ee6911c6?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.decolor.com\/nl\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pinturas DECOLOR en el Festival de los Sentidos","description":"Pinturas DECOLOR impulsando el arte y la creatividad en el Festival de los Sentidos con su estaci\u00f3n para expresarse con la pintura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.decolor.com\/nl\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/","og_locale":"nl_NL","og_type":"article","og_title":"Pinturas DECOLOR en el Festival de los Sentidos","og_description":"Pinturas DECOLOR impulsando el arte y la creatividad en el Festival de los Sentidos con su estaci\u00f3n para expresarse con la pintura.","og_url":"https:\/\/www.decolor.com\/nl\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/","og_site_name":"Decolor","article_published_time":"2024-05-07T10:00:03+00:00","article_modified_time":"2024-07-01T12:23:42+00:00","og_image":[{"width":920,"height":600,"url":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/FESTIVAL-DE-LOS-SENTIDOS-Pinturas-Decolor-BLOG.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/FESTIVAL-DE-LOS-SENTIDOS-Pinturas-Decolor-BLOG.png","twitter_misc":{"Geschreven door":"admin","Geschatte leestijd":"4 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#article","isPartOf":{"@id":"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/"},"author":{"name":"admin","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/person\/97caf6fe02baef67513e86a4f3dc9c90"},"headline":"Pinturas DECOLOR impulsando el arte y la creatividad en el Festival de los Sentidos","datePublished":"2024-05-07T10:00:03+00:00","dateModified":"2024-07-01T12:23:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/"},"wordCount":612,"commentCount":0,"publisher":{"@id":"https:\/\/www.decolor.com\/it\/#organization"},"image":{"@id":"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/FESTIVAL-DE-LOS-SENTIDOS-Pinturas-Decolor-BLOG.png","articleSection":["Decolor"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/","url":"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/","name":"Pinturas DECOLOR en el Festival de los Sentidos","isPartOf":{"@id":"https:\/\/www.decolor.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#primaryimage"},"image":{"@id":"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/FESTIVAL-DE-LOS-SENTIDOS-Pinturas-Decolor-BLOG.png","datePublished":"2024-05-07T10:00:03+00:00","dateModified":"2024-07-01T12:23:42+00:00","description":"Pinturas DECOLOR impulsando el arte y la creatividad en el Festival de los Sentidos con su estaci\u00f3n para expresarse con la pintura.","breadcrumb":{"@id":"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#primaryimage","url":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/FESTIVAL-DE-LOS-SENTIDOS-Pinturas-Decolor-BLOG.png","contentUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2024\/05\/FESTIVAL-DE-LOS-SENTIDOS-Pinturas-Decolor-BLOG.png","width":920,"height":600,"caption":"Festival de los Sentidos PINTURAS DECOLOR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.decolor.com\/en\/2024\/05\/07\/pinturas-decolor-impulsando-el-arte-y-la-creatividad-en-el-festival-de-los-sentidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.decolor.com\/"},{"@type":"ListItem","position":2,"name":"Pinturas DECOLOR impulsando el arte y la creatividad en el Festival de los Sentidos"}]},{"@type":"WebSite","@id":"https:\/\/www.decolor.com\/it\/#website","url":"https:\/\/www.decolor.com\/it\/","name":"Kleur","description":"Web ontkleuren","publisher":{"@id":"https:\/\/www.decolor.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.decolor.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.decolor.com\/it\/#organization","name":"Kleur","url":"https:\/\/www.decolor.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png","contentUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png","width":1588,"height":421,"caption":"Decolor"},"image":{"@id":"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/person\/97caf6fe02baef67513e86a4f3dc9c90","name":"beheerder","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/abe407930cb2e3e5c2930411ee6911c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/abe407930cb2e3e5c2930411ee6911c6?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.decolor.com\/nl\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/posts\/147944"}],"collection":[{"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/comments?post=147944"}],"version-history":[{"count":10,"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/posts\/147944\/revisions"}],"predecessor-version":[{"id":148396,"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/posts\/147944\/revisions\/148396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/media\/147948"}],"wp:attachment":[{"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/media?parent=147944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/categories?post=147944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.decolor.com\/nl\/wp-json\/wp\/v2\/tags?post=147944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}