{"id":151105,"date":"2025-07-03T12:25:44","date_gmt":"2025-07-03T12:25:44","guid":{"rendered":"https:\/\/www.decolor.com\/?post_type=ficha-de-seguridad&#038;p=151105"},"modified":"2025-07-03T12:25:44","modified_gmt":"2025-07-03T12:25:44","slug":"20117_albor-brillo-tabaco-355_es","status":"publish","type":"ficha-de-seguridad","link":"https:\/\/www.decolor.com\/pl\/ficha-de-seguridad\/20117_albor-brillo-tabaco-355_es\/","title":{"rendered":"20117_ALBOR BRILLO TABACO 355_ES"},"template":"","class_list":["post-151105","ficha-de-seguridad","type-ficha-de-seguridad","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>20117_ALBOR BRILLO TABACO 355_ES - Decolor<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20117_ALBOR BRILLO TABACO 355_ES - Decolor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.decolor.com\/pl\/ficha-de-seguridad\/20117_albor-brillo-tabaco-355_es\/\" \/>\n<meta property=\"og:site_name\" content=\"Decolor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/ficha-de-seguridad\\\/20117_albor-brillo-tabaco-355_es\\\/\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/ficha-de-seguridad\\\/20117_albor-brillo-tabaco-355_es\\\/\",\"name\":\"20117_ALBOR BRILLO TABACO 355_ES - Decolor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#website\"},\"datePublished\":\"2025-07-03T12:25:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/ficha-de-seguridad\\\/20117_albor-brillo-tabaco-355_es\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.decolor.com\\\/ficha-de-seguridad\\\/20117_albor-brillo-tabaco-355_es\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/ficha-de-seguridad\\\/20117_albor-brillo-tabaco-355_es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.decolor.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fichas de Seguridad\",\"item\":\"https:\\\/\\\/www.decolor.com\\\/es\\\/fichas-de-seguridad\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"20117_ALBOR BRILLO TABACO 355_ES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/\",\"name\":\"Decolor\",\"description\":\"Web Decolor\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#organization\",\"name\":\"Decolor\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/marca_principal_pinturas_decolor_color.png\",\"contentUrl\":\"https:\\\/\\\/www.decolor.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/marca_principal_pinturas_decolor_color.png\",\"width\":1588,\"height\":421,\"caption\":\"Decolor\"},\"image\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"20117_ALBOR BRILLO TABACO 355_ES - Decolor","robots":{"index":"noindex","follow":"follow"},"og_locale":"pl_PL","og_type":"article","og_title":"20117_ALBOR BRILLO TABACO 355_ES - Decolor","og_url":"https:\/\/www.decolor.com\/pl\/ficha-de-seguridad\/20117_albor-brillo-tabaco-355_es\/","og_site_name":"Decolor","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.decolor.com\/ficha-de-seguridad\/20117_albor-brillo-tabaco-355_es\/","url":"https:\/\/www.decolor.com\/ficha-de-seguridad\/20117_albor-brillo-tabaco-355_es\/","name":"20117_ALBOR BRILLO TABACO 355_ES - Decolor","isPartOf":{"@id":"https:\/\/www.decolor.com\/it\/#website"},"datePublished":"2025-07-03T12:25:44+00:00","breadcrumb":{"@id":"https:\/\/www.decolor.com\/ficha-de-seguridad\/20117_albor-brillo-tabaco-355_es\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.decolor.com\/ficha-de-seguridad\/20117_albor-brillo-tabaco-355_es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.decolor.com\/ficha-de-seguridad\/20117_albor-brillo-tabaco-355_es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.decolor.com\/"},{"@type":"ListItem","position":2,"name":"Fichas de Seguridad","item":"https:\/\/www.decolor.com\/es\/fichas-de-seguridad\/"},{"@type":"ListItem","position":3,"name":"20117_ALBOR BRILLO TABACO 355_ES"}]},{"@type":"WebSite","@id":"https:\/\/www.decolor.com\/it\/#website","url":"https:\/\/www.decolor.com\/it\/","name":"Kolor","description":"Odbarwianie sieci","publisher":{"@id":"https:\/\/www.decolor.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.decolor.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/www.decolor.com\/it\/#organization","name":"Kolor","url":"https:\/\/www.decolor.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png","contentUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png","width":1588,"height":421,"caption":"Decolor"},"image":{"@id":"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.decolor.com\/pl\/wp-json\/wp\/v2\/ficha-de-seguridad\/151105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.decolor.com\/pl\/wp-json\/wp\/v2\/ficha-de-seguridad"}],"about":[{"href":"https:\/\/www.decolor.com\/pl\/wp-json\/wp\/v2\/types\/ficha-de-seguridad"}],"wp:attachment":[{"href":"https:\/\/www.decolor.com\/pl\/wp-json\/wp\/v2\/media?parent=151105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}