{"id":143767,"date":"2024-02-21T08:24:38","date_gmt":"2024-02-21T08:24:38","guid":{"rendered":"https:\/\/decolor.es\/?post_type=ficha-de-seguridad&#038;p=143767"},"modified":"2024-02-21T08:24:38","modified_gmt":"2024-02-21T08:24:38","slug":"13610_decokril-penetrante_es-pdf","status":"publish","type":"ficha-de-seguridad","link":"https:\/\/www.decolor.com\/zh\/ficha-de-seguridad\/13610_decokril-penetrante_es-pdf\/","title":{"rendered":"13610_DECOKRIL PENETRANTE_EN.pdf"},"template":"","class_list":["post-143767","ficha-de-seguridad","type-ficha-de-seguridad","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>13610_DECOKRIL PENETRANTE_ES.pdf - Decolor<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"13610_DECOKRIL PENETRANTE_ES.pdf - Decolor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.decolor.com\/zh\/ficha-de-seguridad\/13610_decokril-penetrante_es-pdf\/\" \/>\n<meta property=\"og:site_name\" content=\"Decolor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/zh\\\/ficha-de-seguridad\\\/13610_decokril-penetrante_es-pdf\\\/\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/zh\\\/ficha-de-seguridad\\\/13610_decokril-penetrante_es-pdf\\\/\",\"name\":\"13610_DECOKRIL PENETRANTE_ES.pdf - Decolor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#website\"},\"datePublished\":\"2024-02-21T08:24:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/zh\\\/ficha-de-seguridad\\\/13610_decokril-penetrante_es-pdf\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.decolor.com\\\/zh\\\/ficha-de-seguridad\\\/13610_decokril-penetrante_es-pdf\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/zh\\\/ficha-de-seguridad\\\/13610_decokril-penetrante_es-pdf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.decolor.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fichas de Seguridad\",\"item\":\"https:\\\/\\\/www.decolor.com\\\/es\\\/fichas-de-seguridad\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"13610_DECOKRIL PENETRANTE_ES.pdf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/\",\"name\":\"Decolor\",\"description\":\"Web Decolor\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#organization\",\"name\":\"Decolor\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.decolor.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/marca_principal_pinturas_decolor_color.png\",\"contentUrl\":\"https:\\\/\\\/www.decolor.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/marca_principal_pinturas_decolor_color.png\",\"width\":1588,\"height\":421,\"caption\":\"Decolor\"},\"image\":{\"@id\":\"https:\\\/\\\/www.decolor.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"13610_DECOKRIL PENETRANT_ES.pdf - \u8131\u8272","robots":{"index":"noindex","follow":"follow"},"og_locale":"zh_CN","og_type":"article","og_title":"13610_DECOKRIL PENETRANTE_ES.pdf - Decolor","og_url":"https:\/\/www.decolor.com\/zh\/ficha-de-seguridad\/13610_decokril-penetrante_es-pdf\/","og_site_name":"Decolor","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.decolor.com\/zh\/ficha-de-seguridad\/13610_decokril-penetrante_es-pdf\/","url":"https:\/\/www.decolor.com\/zh\/ficha-de-seguridad\/13610_decokril-penetrante_es-pdf\/","name":"13610_DECOKRIL PENETRANT_ES.pdf - \u8131\u8272","isPartOf":{"@id":"https:\/\/www.decolor.com\/it\/#website"},"datePublished":"2024-02-21T08:24:38+00:00","breadcrumb":{"@id":"https:\/\/www.decolor.com\/zh\/ficha-de-seguridad\/13610_decokril-penetrante_es-pdf\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.decolor.com\/zh\/ficha-de-seguridad\/13610_decokril-penetrante_es-pdf\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.decolor.com\/zh\/ficha-de-seguridad\/13610_decokril-penetrante_es-pdf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.decolor.com\/"},{"@type":"ListItem","position":2,"name":"Fichas de Seguridad","item":"https:\/\/www.decolor.com\/es\/fichas-de-seguridad\/"},{"@type":"ListItem","position":3,"name":"13610_DECOKRIL PENETRANTE_ES.pdf"}]},{"@type":"WebSite","@id":"https:\/\/www.decolor.com\/it\/#website","url":"https:\/\/www.decolor.com\/it\/","name":"\u989c\u8272","description":"\u7f51\u9875\u8131\u8272","publisher":{"@id":"https:\/\/www.decolor.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.decolor.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/www.decolor.com\/it\/#organization","name":"\u989c\u8272","url":"https:\/\/www.decolor.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png","contentUrl":"https:\/\/www.decolor.com\/wp-content\/uploads\/2021\/02\/marca_principal_pinturas_decolor_color.png","width":1588,"height":421,"caption":"Decolor"},"image":{"@id":"https:\/\/www.decolor.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.decolor.com\/zh\/wp-json\/wp\/v2\/ficha-de-seguridad\/143767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.decolor.com\/zh\/wp-json\/wp\/v2\/ficha-de-seguridad"}],"about":[{"href":"https:\/\/www.decolor.com\/zh\/wp-json\/wp\/v2\/types\/ficha-de-seguridad"}],"wp:attachment":[{"href":"https:\/\/www.decolor.com\/zh\/wp-json\/wp\/v2\/media?parent=143767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}